{"id":104,"date":"2017-02-21T20:44:27","date_gmt":"2017-02-21T20:44:27","guid":{"rendered":"http:\/\/www.tripsmachupicchu.com\/es\/?p=104"},"modified":"2017-02-21T20:44:27","modified_gmt":"2017-02-21T20:44:27","slug":"machu-picchu-3d-2n","status":"publish","type":"post","link":"https:\/\/www.funtripsperu.com\/es\/machu-picchu-3d-2n\/","title":{"rendered":"MACHU PICCHU 3 DAYS 2 NIGHTS"},"content":{"rendered":"<p>El encanto y la magia de este magico e inolvidable lugar con la major compa\u00f1ia de Colors International. Encuentre en Machupicchu la magia de un y de las 7 maravillas del mundo y viaje en su historia.<\/p>\n<p><em>DIA 1<\/em><\/p>\n<p><em>A su llegada, recepci\u00f3n por nuestros colaboradores y traslado a la estaci\u00f3n de Ollantaytambo donde abordaremos nuestro tren con destino a Machu Picchu. A su llegada nuestro staff lo trasladara al hotel y lo ayudar\u00e1 a registrarse. Alojamiento en Machu Picchu Pueblo.<\/em><\/p>\n<p><em>DIA 2<\/em><\/p>\n<p><em>Desayuno. Por la ma\u00f1ana nuestros colaboradores lo asistir\u00e1n para abordar el bus que los conducir\u00e1 a <strong>La<\/strong> <strong>Ciudadela de \u201cMachu Picchu\u201d<\/strong>, para poder apreciar el amanecer. En el recorrido podr\u00e1 apreciar el ca\u00f1\u00f3n del r\u00edo Urubamba. Ingresaremos a la ciudadela y nos adentraremos por sus terrazas, escalinatas, recintos ceremoniales y lugares de vivienda.\u00a0 Luego despu\u00e9s de la visita guiada, dispondr\u00e1 de tiempo libre para explorar el lugar por su cuenta, relajarse o meditar. A la hora apropiada, descenderemos al pueblo de Machupichu para disfrutar de un <strong>Almuerzo buffet.<\/strong><\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<table>\n<tbody>\n<tr>\n<td><em>Por la tarde retorno en tren. A su llegada nuestros colaboradores lo esperaran en la estaci\u00f3n de Poroy, desde donde los trasladaremos hasta su hotel. Alojamiento en Cusco.<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>DIA 3<\/em><\/p>\n<p><em>Desayuno. En hora oportuna, traslado al aeropuerto para abordar su vuelo.<\/em><\/p>\n<p><strong><em><u>Incluye: <\/u><\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>En Machu Picchu:<\/em><\/strong><\/p>\n<p><em>Recepci\u00f3n y asistencia en el embarque y desembarque en la estaci\u00f3n de trenes y Machu Picchu Pueblo<\/em><\/p>\n<p><em>Excursi\u00f3n de d\u00eda entero a Machu Picchu con almuerzo Buffet en Machu Picchu <\/em><\/p>\n<p><em>01 noche de hospedaje en Machu Picchu Pueblo con desayuno e impuestos<\/em><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>En Cusco:<\/em><\/strong><\/p>\n<p><em>Traslados Aeropuerto\/Estaci\u00f3n de Tren\/Hotel\/Aeropuerto y asistencia <\/em><\/p>\n<p><em>01 noche de hospedaje en Machu Picchu Pueblo con desayuno e impuestos<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<ul>\n<li><em>Todos los desayunos y alimentaci\u00f3n mencionados en el programa<\/em><\/li>\n<li><em>Todas las entradas e ingresos a las excursiones mencionadas en el itinerario <\/em><\/li>\n<li><em>Todos los traslados y transportes terrestres mencionados <\/em><\/li>\n<li><strong><em>Boletos de Trenes ida y retorno ( a elecci\u00f3n del cliente)<\/em><\/strong><\/li>\n<li><em>Todos los impuestos aplicables <\/em><\/li>\n<li><strong><em>Gu\u00edas biling\u00fces (Ingles\/ Espa\u00f1ol) en todas las excursiones mencionadas en el programa <\/em><\/strong><\/li>\n<li><strong><em>Asistencia completa durante su estad\u00eda Travel Concierge<\/em><\/strong><\/li>\n<li><strong><em>Kit de bienvenida con ingresos y vouchers<\/em><\/strong><\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El encanto y la magia de este magico e inolvidable lugar con la major compa\u00f1ia de Colors International. Encuentre en Machupicchu la magia de un y de las 7 maravillas del mundo y viaje en su historia. DIA 1 A su llegada, recepci\u00f3n por nuestros colaboradores y traslado a la estaci\u00f3n de Ollantaytambo donde abordaremos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-104","post","type-post","status-publish","format-standard","hentry","category-cusco-tours"],"_links":{"self":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":0,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts\/104\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/media?parent=104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/categories?post=104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/tags?post=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}