{"id":371,"date":"2017-10-24T02:26:47","date_gmt":"2017-10-24T02:26:47","guid":{"rendered":"http:\/\/www.tripsmachupicchu.com\/?p=371"},"modified":"2021-08-14T16:21:56","modified_gmt":"2021-08-14T16:21:56","slug":"rainbow-mountain","status":"publish","type":"post","link":"https:\/\/www.funtripsperu.com\/es\/rainbow-mountain\/","title":{"rendered":"RAINBOW MOUNTAIN TRIP"},"content":{"rendered":"<p>Conozca la \u00fanica monta\u00f1a en el mundo que parece un arco\u00edris. Disfrute del color y el misticismo que envuelve su imponente figura. Atraviese sus valles y d\u00e9jese llevar por la magia y el color de esta impresionante monta\u00f1a.<\/p>\n<p><em>Temprano por la ma\u00f1ana traslado desde el cusco para pasar por varios pueblos peque\u00f1os como, Checacupe, Pitumarka y Chilca. Llegando al poblado de Pampachiri a unos 3800 m.s.n.m. Breve explicaci\u00f3n del recorrido a cargo de nuestro gu\u00eda antes de tomar e desayuno para aclimatarnos adecuadamente.<\/em><\/p>\n<p><em>Disfrutando de vistas espectaculares y coloridas como el imponente Apu Ausangate, recorreremos un trayecto de Aprox. 4 horas para finalmente llegar a la cima de la monta\u00f1a. El retorno tomara 3 horas m\u00e1s. Almuerzo incluido a mitad del camino hacia Panpachiri. De este punto abordaremos nuevamente nuestro transporte que nos llevar\u00e1 de regreso a Cusco, el tour terminara a las 19:00 horas en la Plaza de Armas del Cusco.<\/em><\/p>\n<p><strong>El servicio del tour incluye:<\/strong><\/p>\n<ul>\n<li>Transporte para todo el recorrido.<\/li>\n<li>Gu\u00eda profesional especializado.<\/li>\n<li>Box lunch.<\/li>\n<\/ul>\n<p><strong>El servicio del tour No incluye:<\/strong><\/p>\n<ul>\n<li>Bebidas como Agua<\/li>\n<li>Llamadas de tel\u00e9fono<\/li>\n<\/ul>\n<p><strong>Se recomienda:<\/strong><\/p>\n<ul>\n<li>Llevar ropa abrigadora y tambi\u00e9n liviana<\/li>\n<li>Crema bloquedora y sombrero<\/li>\n<li>Bebidas rehidratantes<\/li>\n<li>C\u00e1mara fotogr\u00e1fica<\/li>\n<li>Poncho para la lluvia (opcional)<\/li>\n<\/ul>\n<p><strong>Precio por persona:<\/strong><\/p>\n<table style=\"border: 1px !important;\">\n<tbody>\n<tr>\n<td width=\"70\"><strong>N\u00b0 People<\/strong><\/td>\n<td width=\"70\"><strong>1 persona<\/strong><\/td>\n<td width=\"70\"><strong>2 personas<\/strong><\/td>\n<td width=\"70\"><strong>3 personas<\/strong><\/td>\n<td width=\"82\"><strong>mas personas<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Servicio Grupal<\/strong><\/td>\n<td>60 $ USD<\/td>\n<td>55 $ USD<\/td>\n<td>50 $ USD<\/td>\n<td>45 $ USD<\/td>\n<\/tr>\n<tr>\n<td><strong>Servicio Privado<\/strong><\/td>\n<td>209 $ USD<\/td>\n<td>139 $ USD<\/td>\n<td>119 $ USD<\/td>\n<td>108 $ USD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>El servicio privado incluye: &#8211; tickets de entrada a lugares arqueol\u00f3gicos y almuerzo bufet.<\/p>\n<p>En el servicio privado: usted\u00a0 escoge el lugar tur\u00edstico onde desea pasar mas tiempo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Conozca la \u00fanica monta\u00f1a en el mundo que parece un arco\u00edris. Disfrute del color y el misticismo que envuelve su imponente figura. Atraviese sus valles y d\u00e9jese llevar por la magia y el color de esta impresionante monta\u00f1a. Temprano por la ma\u00f1ana traslado desde el cusco para pasar por varios pueblos peque\u00f1os como, Checacupe, Pitumarka&#8230;<\/p>\n","protected":false},"author":1,"featured_media":574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,13,10,12],"tags":[],"class_list":["post-371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cusco-tours","category-day-tours","category-portada","category-trekkings"],"_links":{"self":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":2,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"predecessor-version":[{"id":604,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/posts\/371\/revisions\/604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/media\/574"}],"wp:attachment":[{"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/categories?post=371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.funtripsperu.com\/es\/wp-json\/wp\/v2\/tags?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}